{"id":1026156,"date":"2021-04-01T11:36:17","date_gmt":"2021-04-01T08:36:17","guid":{"rendered":"https:\/\/www.etoro.com\/editorial\/\/pawel-majtkowski\/"},"modified":"2025-03-14T13:32:56","modified_gmt":"2025-03-14T11:32:56","slug":"pawel-majtkowski","status":"publish","type":"analyst","link":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/","title":{"rendered":"Pawel Majtkowski"},"content":{"rendered":"\n<div class=\"wp-block-etoro-half-cover has-product-black-background-color\">\n<div class=\"wp-block-etoro-half-cover-left\"><p id=\"breadcrumbs\" class=\"gray-dark\"><span><span><a href=\"https:\/\/www.etoro.com\/it\/\">Home<\/a><\/span><\/span><\/p>\n<h2 class=\"wp-block-heading is-style-banner-title\">\n\t    <b class=\"wp-etoro-format-colored-dark-blue\">Pawel<\/b> Majtkowski<\/h2>\n<p class=\"is-style-subtitle\">Analista del mercato polacco presso eToro<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-etoro-half-cover-right\">\n<img decoding=\"async\" src=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel.png\" alt=\"\" class=\"wp-block-etoro-half-cover-media\"\/><img decoding=\"async\" src=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel.png\" alt=\"\" class=\"wp-block-etoro-half-cover-media-desktop\"\/><img decoding=\"async\" src=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\" alt=\"\" class=\"wp-block-etoro-half-cover-media-tablet\"\/><img decoding=\"async\" src=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\" alt=\"\" class=\"wp-block-etoro-half-cover-media-mobile\"\/>\n<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-etoro-box wp-block-etoro-box-align-start wp-block-etoro-box-size-14\"><p><span style=\"font-weight: 400;\">Pawe\u0142 \u00e8 l\u2019analista di mercato di punta di eToro per la Polonia, con oltre 18 anni di esperienza. Rinomato per la sua competenza in azioni, analisi macroeconomica e finanza personale, fornisce regolarmente riflessioni e approfondimenti agli investitori retail tramite vari mezzi di comunicazione.<\/span><\/p>\n\n<div class=\"wp-block-etoro-author-details\">\n    <p><strong>Esperienze e competenze:<\/strong><\/p>\n    <ul class=\"wp-block-list wp-block-list-check\">\n        <li>Azioni polacche<\/li><li>Mercati azionari<\/li><li>Analisi fondamentale delle azioni<\/li><li>Analisi macroeconomica<\/li><li>Gestione del rischio <\/li><li>Finanza personale<\/li>    <\/ul>\n<\/div>\n<div class=\"wp-block-etoro-follow-networks wp-block-etoro-follow-networks-align-start\">\n    <div class=\"wp-block-etoro-follow-networks-title\">\n        Segui Pawel Majtkowski sui social media:\n    <\/div>\n    <div class=\"wp-block-etoro-follow-networks-list\">\n                    <a class=\"wp-block-etoro-follow-network\" href=\"https:\/\/www.etoro.com\/people\/pmajtkowski\" title=\"eToro\" target=\"_blank\"\n                rel=\"noopener noreferrer\">\n                <svg width=\"50\" height=\"51\" viewBox=\"0 0 50 51\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    aria-hidden=\"true\">\n                    <rect x=\"0.000488281\" y=\"0.75\" width=\"50\" height=\"50\" rx=\"25\" fill=\"#13C636\"><\/rect>\n                    <g clip-path=\"url(#clip0_78_3174)\">\n                        <path\n                            d=\"M31.818 21.0447C31.5767 20.8292 31.4475 20.668 31.6411 20.668C32.0482 20.668 34.5125 21.0289 35.0219 19.1811C35.5314 17.3333 32.8114 11.7597 32.7095 11.5202C32.6104 11.2908 32.8142 10.9994 33.1124 10.9994C33.4107 10.9994 33.6219 11.3149 33.6515 11.3534C36.4252 14.8053 40.2974 19.1153 40.7958 20.9724C42.0578 25.6777 37.1787 27.5843 34.1017 27.9328C34.0916 27.9344 34.0813 27.9338 34.0715 27.931C34.0617 27.9283 34.0526 27.9234 34.0449 27.9168C34.0371 27.9102 34.0309 27.902 34.0267 27.8928C34.0224 27.8835 34.0202 27.8735 34.0202 27.8633V26.1924C34.0202 23.9383 33.1699 22.2503 31.8203 21.0447H31.818ZM18.182 21.0447C16.8329 22.2494 15.9826 23.9383 15.9826 26.1924V27.8633C15.9825 27.8734 15.9803 27.8835 15.976 27.8927C15.9717 27.9019 15.9655 27.91 15.9577 27.9166C15.95 27.9232 15.9409 27.9281 15.9312 27.9309C15.9214 27.9336 15.9112 27.9343 15.9011 27.9328C12.8213 27.5843 7.94222 25.6777 9.20425 20.9738C9.70304 19.1153 13.5748 14.8053 16.3485 11.3538C16.3795 11.3154 16.5944 10.9999 16.8876 10.9999C17.1807 10.9999 17.3891 11.2913 17.29 11.5202C17.1872 11.7593 14.47 17.3333 14.9781 19.1807C15.4861 21.028 17.9514 20.6675 18.3589 20.6675C18.5539 20.6675 18.4233 20.8288 18.182 21.0442V21.0447ZM25.148 20.2653C28.4362 20.2982 31.9134 22.2378 31.9134 26.1498V29.4229C31.9134 29.541 31.8903 29.6579 31.8451 29.7671C31.8 29.8762 31.7339 29.9754 31.6504 30.059C31.567 30.1425 31.4679 30.2088 31.3589 30.2541C31.2498 30.2993 31.133 30.3226 31.0149 30.3227H21.7222V32.1006C21.7222 33.7116 23.6359 34.6323 25.1494 34.6323C26.2641 34.6323 27.8499 34.061 28.4714 33.0259C28.4755 33.0164 28.4817 33.008 28.4895 33.0013C28.4973 32.9945 28.5065 32.9896 28.5165 32.9869C28.5264 32.9841 28.5368 32.9836 28.547 32.9854C28.5571 32.9872 28.5667 32.9912 28.5751 32.9971C29.7121 33.6379 30.3781 34.0021 31.5257 34.6605C31.5601 34.6794 31.5857 34.7109 31.5972 34.7483C31.6087 34.7858 31.6052 34.8263 31.5873 34.8612C30.2855 36.968 27.5512 37.9623 25.1498 37.986C21.7977 37.9535 18.1102 36.0788 18.1102 32.1015V26.1517C18.1102 22.2378 21.7991 20.2982 25.1498 20.2672L25.148 20.2653ZM28.3723 27.1812V26.1507C28.3723 24.5388 26.5596 23.7831 25.1466 23.7831C23.6345 23.7831 21.7194 24.5388 21.7194 26.1507V27.3313H28.2227C28.2431 27.3315 28.2634 27.3275 28.2822 27.3195C28.301 27.3116 28.3179 27.2998 28.332 27.285C28.3583 27.2573 28.3727 27.2204 28.3723 27.1821V27.1812Z\"\n                            fill=\"white\"><\/path>\n                    <\/g>\n                    <defs>\n                        <clipPath id=\"clip0_78_3174\">\n                            <rect width=\"32\" height=\"26.988\" fill=\"white\" transform=\"translate(9 11)\"><\/rect>\n                        <\/clipPath>\n                    <\/defs>\n                <\/svg>\n            <\/a>\n                            <a class=\"wp-block-etoro-follow-network\" href=\"https:\/\/www.linkedin.com\/in\/majtkowski\/\" title=\"LinkedIn\" target=\"_blank\"\n                rel=\"noopener noreferrer\">\n                <svg width=\"51\" height=\"51\" viewBox=\"0 0 51 51\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    aria-hidden=\"true\">\n                    <rect x=\"0.5\" y=\"0.551758\" width=\"50.0001\" height=\"50.0001\" rx=\"25\" fill=\"#0072B1\"><\/rect>\n                    <g clip-path=\"url(#clip0_929_9838)\">\n                        <path\n                            d=\"M39.5596 38.052V28.3206C39.5596 23.542 38.5317 19.8687 32.9582 19.8687C31.9121 19.8299 30.8752 20.0761 29.9578 20.581C29.0404 21.0859 28.2769 21.8306 27.7486 22.7359H27.6747V20.3103H22.394V38.052H27.895V29.2821C27.895 26.9669 28.33 24.7257 31.1965 24.7257C34.021 24.7257 34.0572 27.375 34.0572 29.4317V38.0593L39.5596 38.052Z\"\n                            fill=\"white\"><\/path>\n                        <path\n                            d=\"M16.1967 11.4893C15.3507 11.4893 14.5393 11.8259 13.9411 12.4252C13.3429 13.0244 13.0068 13.8372 13.0068 14.6847C13.0068 15.5321 13.3429 16.3449 13.9411 16.9442C14.5393 17.5434 15.3507 17.8801 16.1967 17.8801C17.0427 17.8784 17.8537 17.5416 18.4527 16.9432C19.0502 16.3445 19.386 15.5327 19.3865 14.6861C19.3867 14.2664 19.3043 13.8507 19.1441 13.4628C18.9839 13.075 18.7489 12.7226 18.4527 12.4257C18.1565 12.1288 17.8048 11.8933 17.4177 11.7326C17.0306 11.572 16.6157 11.4893 16.1967 11.4893Z\"\n                            fill=\"white\"><\/path>\n                        <path d=\"M18.9419 20.3091H13.4365V38.0523H18.9419V20.3091Z\" fill=\"white\"><\/path>\n                    <\/g>\n                    <defs>\n                        <clipPath id=\"clip0_929_9838\">\n                            <rect width=\"26.5626\" height=\"26.5626\" fill=\"white\"\n                                    transform=\"translate(13 11.4893)\"><\/rect>\n                        <\/clipPath>\n                    <\/defs>\n                <\/svg>\n            <\/a>\n                            <a class=\"wp-block-etoro-follow-network\" href=\"https:\/\/x.com\/PawelMajtkowski\" title=\"X\" target=\"_blank\"\n                rel=\"noopener noreferrer\">\n                <svg width=\"50\" height=\"51\" viewBox=\"0 0 50 51\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n                    aria-hidden=\"true\">\n                    <rect x=\"0.000488281\" y=\"0.75\" width=\"50\" height=\"50\" rx=\"25\" fill=\"black\"><\/rect>\n                    <g clip-path=\"url(#clip0_1552_10216)\">\n                        <path\n                            d=\"M27.474 23.7591L37.1531 12.75H34.8588L26.4552 22.3092L19.7426 12.75H12.0005L22.1511 27.2051L12.0005 38.75H14.2943L23.1694 28.6552L30.2583 38.75H38.0005L27.4735 23.7591H27.474ZM24.3323 27.3325L23.304 25.893L15.1205 14.4395H18.6435L25.2475 23.683L26.276 25.1226L34.8603 37.1375H31.3376L24.3323 27.333V27.3325Z\"\n                            fill=\"white\"><\/path>\n                    <\/g>\n                    <defs>\n                        <clipPath id=\"clip0_1552_10216\">\n                            <rect width=\"26\" height=\"26\" fill=\"white\" transform=\"translate(12.0005 12.75)\"><\/rect>\n                        <\/clipPath>\n                    <\/defs>\n                <\/svg>\n            <\/a>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed has-product-black-background-color has-background\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Articoli di Pawe\u0142<\/h2>\n\n\n\n<hr class=\"wp-block-separator wp-block-separator-color-light-grey wp-block-separator-spaces-zero wp-block-separator-weight-2\"\/>\n\n\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed has-product-black-background-color has-background\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Maggiori informazioni su Pawe\u0142<\/h2>\n\n\n\n<hr class=\"wp-block-separator wp-block-separator-color-light-grey wp-block-separator-spaces-zero wp-block-separator-weight-2\"\/>\n\n\n\n<div class=\"wp-block-etoro-box wp-block-etoro-box-align-start wp-block-etoro-box-size-14\">\n<ul class=\"wp-block-list wp-block-list wp-block-list-circle\">\n<li>Pawe\u0142 \u00e8 un analista di mercato autorevole presso eToro, specializzato nel mercato polacco.<\/li>\n\n\n\n<li>Oltre 18 anni di esperienza in istituzioni finanziarie.<\/li>\n\n\n\n<li>Esperto di riferimento per le azioni polacche, con competenze sviluppate in mercati azionari, analisi fondamentale delle azioni, analisi macroeconomica e finanza personale.<\/li>\n\n\n\n<li>Offre riflessioni e spunti su questioni finanziarie tramite vari mezzi di comunicazione.<\/li>\n\n\n\n<li>Uno degli esperti di mercato finanziario pi\u00f9 citati in Polonia.<\/li>\n\n\n\n<li>Supporta gli investitori al dettaglio nella comprensione dei mercati finanziari.<\/li>\n<\/ul>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed has-product-black-background-color has-background\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Esperienza<\/h2>\n\n\n\n<hr class=\"wp-block-separator wp-block-separator-color-light-grey wp-block-separator-spaces-zero wp-block-separator-weight-2\"\/>\n\n\n\n<div class=\"wp-block-etoro-box wp-block-etoro-box-align-start wp-block-etoro-box-size-14\">\n<ul class=\"wp-block-list wp-block-list wp-block-list-circle\">\n<li>Lavora nel mercato finanziario dal 2006.&nbsp;<\/li>\n\n\n\n<li>Dal 2006 al 2012, ha lavorato presso Expander Advisory come analista e successivamente come capo analista.<\/li>\n\n\n\n<li>Dal 2013 al 2014, \u00e8 stato analista capo presso Poczta Polska, l&#8217;operatore postale nazionale in Polonia e proprietario del Postal Bank.<\/li>\n\n\n\n<li>Dal 2014 al 2015, \u00e8 stato analista capo presso la filiale polacca di Aviva.<\/li>\n\n\n\n<li>Successivamente, ha gestito un&#8217;attivit\u00e0 di consulenza finanziaria.<\/li>\n\n\n\n<li>Dal 2021, \u00e8 analista polacco presso eToro.<\/li>\n<\/ul>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Percorso di studi e certificazioni<\/h2>\n\n\n\n<hr class=\"wp-block-separator wp-block-separator-color-light-grey wp-block-separator-spaces-zero wp-block-separator-weight-2\"\/>\n\n\n\n<div class=\"wp-block-etoro-box wp-block-etoro-box-align-start wp-block-etoro-box-size-14\"><ul class=\"wp-block-list wp-block-list-check\">\n<li><span style=\"font-weight: 400;\">Laurea magistrale in Giurisprudenza presso l&#8217;Universit\u00e0 di Varsavia.<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-etoro-box wp-block-etoro-box-align-center wp-block-etoro-box-size-14\">\n<p class=\"has-text-align-center\">Visualizza il portafoglio di Pawe\u0142, aggiungilo alla tua lista dei preferiti e ricevi una notifica ogni volta che pubblica qualcosa di nuovo.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<a class=\"e-cta e-cta-primary\" href=\"https:\/\/www.etoro.com\/people\/pmajtkowski\">Segui Pawe\u0142<\/a>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-etoro-related-pages has-carbon-olive-background-color wp-etoro-block-related-pages\"><div class=\"wp-etoro-block-related-pages-to-center\"><div class=\"wp-etoro-block-related-pages-menu-name\">Pagine correlate:<\/div><div class=\"wp-etoro-block-related-pages-list-container\"><div class=\"wp-etoro-block-related-pages-arrow-left\"><button><\/button><\/div><div class=\"wp-etoro-block-related-pages-list\">\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\"><\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\"><\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\"><\/a><\/div>\n<\/div><div class=\"wp-etoro-block-related-pages-arrow-right\"><button><\/button><\/div><\/div><\/div><\/div>\n","protected":false},"featured_media":1015715,"menu_order":0,"template":"","class_list":["post-1026156","analyst","type-analyst","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Pawe\u0142 Majtkowski | Analista eToro<\/title>\n<meta name=\"description\" content=\"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst\/1026156\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pawe\u0142 Majtkowski | Analista eToro\" \/>\n<meta property=\"og:description\" content=\"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst\/1026156\" \/>\n<meta property=\"og:site_name\" content=\"eToro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eToro\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T11:32:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eToro\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/\",\"url\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/\",\"name\":\"Pawe\u0142 Majtkowski | Analista eToro\",\"isPartOf\":{\"@id\":\"https:\/\/www.etoro.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\",\"datePublished\":\"2021-04-01T08:36:17+00:00\",\"dateModified\":\"2025-03-14T11:32:56+00:00\",\"description\":\"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#breadcrumb\"},\"inLanguage\":\"it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage\",\"url\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\",\"contentUrl\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png\",\"width\":640,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.etoro.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pawel Majtkowski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.etoro.com\/it\/#website\",\"url\":\"https:\/\/www.etoro.com\/it\/\",\"name\":\"eToro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.etoro.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.etoro.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it\"},[]]}<\/script>","yoast_head_json":{"title":"Pawe\u0142 Majtkowski | Analista eToro","description":"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst\/1026156","og_locale":"it_IT","og_type":"article","og_title":"Pawe\u0142 Majtkowski | Analista eToro","og_description":"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.","og_url":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst\/1026156","og_site_name":"eToro","article_publisher":"https:\/\/www.facebook.com\/eToro\/","article_modified_time":"2025-03-14T11:32:56+00:00","og_image":[{"width":640,"height":450,"url":"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eToro","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/","url":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/","name":"Pawe\u0142 Majtkowski | Analista eToro","isPartOf":{"@id":"https:\/\/www.etoro.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage"},"image":{"@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png","datePublished":"2021-04-01T08:36:17+00:00","dateModified":"2025-03-14T11:32:56+00:00","description":"Pawe\u0142 Majtkowski \u00e8 un analista di mercato polacco di eToro con oltre 18 anni di esperienza in mercati azionari, scenari macro e finanza personale.","breadcrumb":{"@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#breadcrumb"},"inLanguage":"it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/"]}]},{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#primaryimage","url":"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png","contentUrl":"https:\/\/www.etoro.com\/wp-content\/uploads\/2021\/04\/Pawel2.png","width":640,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.etoro.com\/it\/editorial\/analysts\/pawel-majtkowski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.etoro.com\/it\/"},{"@type":"ListItem","position":2,"name":"Pawel Majtkowski"}]},{"@type":"WebSite","@id":"https:\/\/www.etoro.com\/it\/#website","url":"https:\/\/www.etoro.com\/it\/","name":"eToro","description":"","publisher":{"@id":"https:\/\/www.etoro.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.etoro.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it"},[]]}},"_links":{"self":[{"href":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst\/1026156"}],"collection":[{"href":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/analyst"}],"about":[{"href":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/types\/analyst"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/media\/1015715"}],"wp:attachment":[{"href":"https:\/\/www.etoro.com\/it\/wp-json\/wp\/v2\/media?parent=1026156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}