{"id":854950,"date":"2024-01-18T09:52:20","date_gmt":"2024-01-18T07:52:20","guid":{"rendered":"https:\/\/www.etoro.com\/trading\/fees\/cfd-spreads\/"},"modified":"2024-03-19T10:48:09","modified_gmt":"2024-03-19T08:48:09","slug":"cfd-spreads","status":"publish","type":"page","link":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/","title":{"rendered":"CDF-spreads"},"content":{"rendered":"\n<section class=\"wp-block-group wp-block-group-boxed wp-block-group-medium-top-padding wp-block-group-medium-bottom-padding\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-top wp-block-columns-1 is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Spreaden \u00e4r skillnaden mellan k\u00f6p- och s\u00e4ljkursen f\u00f6r en viss tillg\u00e5ng.<br>Spreads \u00e4r ett vanligt s\u00e4tt f\u00f6r handelsplattformar att ta ut avgifter.<\/p>\n\n\n\n<hr class=\"wp-block-separator wp-block-separator-color-light-grey wp-block-separator-spaces-medium wp-block-separator-weight-1\"\/>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-group wp-block-group-boxed wp-block-group-medium-top-padding wp-block-group-medium-bottom-padding\"><div class=\"wp-block-group-inner is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-top wp-block-columns-1 is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-etoro-collapsable-items\"><div class=\"wp-block-etoro-collapsable-items-top-part wp-block-etoro-collapsable-items-top-part-no-description\"><div class=\"wp-block-etoro-collapsable-items-description\"><\/div><button class=\"wp-block-etoro-collapsable-items-button e-cta e-cta-alternative-bordered\" data-collapsed=\"\u00d6pppna alla flikar\" data-expanded=\"St\u00e4ng alla flikar\">\u00d6pppna alla flikar<\/button><\/div>\n<div id=\"\" class=\"wp-block-etoro-collapsable-item wp-block-etoro-collapsable-item-collapsable\"><div class=\"wp-block-etoro-collapsable-item-top-part\"><h2 class=\"wp-block-etoro-collapsable-item-title\"><small>Valutor<\/small><\/h2><\/div><div class=\"wp-block-etoro-collapsable-item-content-wrapper\"><div class=\"wp-block-etoro-collapsable-item-content\">\n\t<div class=\"wp-block-etoro-instruments-fees-table\" data-table-type=\"cat_37\">\n\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-wrapper\">\n\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-icon\">\n\t\t\t\t<input class=\"wp-block-etoro-instruments-fees-table-search\" type=\"text\" placeholder=\"S\u00f6k instrument\"\/>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<figure class=\"wp-block-table\">\n\t\t    <div class=\"wp-block-table-content\">\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-left\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-left\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-right\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-right\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-table\">\n\t\t            <table>\n                        <thead>\n                        <tr><th>Valutor<\/th><th>Fr\u00e5n 1 PIP <e-tip><sup>Pip st\u00e5r f\u00f6r &#8220;procent i punkt&#8221;. En pip \u00e4r den minsta prisf\u00f6r\u00e4ndring som en viss v\u00e4xelkurs kan g\u00f6ra, och avser d\u00e4rf\u00f6r den allra sista siffran i ett pris. En pip anv\u00e4nds f\u00f6r att m\u00e4ta prisf\u00f6r\u00e4ndringen f\u00f6r en valuta i f\u00f6rh\u00e5llande till en annan.<\/sup><\/e-tip><\/th>\n                        <\/tr>\n                        <\/thead>\n                        <tbody>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"eurusd eur\/usd\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-1\"><a href=\"\/sv\/markets\/eurusd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-usd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURUSD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/USD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"usdjpy usd\/jpy\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-5\"><a href=\"\/sv\/markets\/usdjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"gbpusd gbp\/usd\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-2\"><a href=\"\/sv\/markets\/gbpusd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-usd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPUSD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/USD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 2<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"usdchf usd\/chf\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-6\"><a href=\"\/sv\/markets\/usdchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1.5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"nzdusd nzd\/usd\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-3\"><a href=\"\/sv\/markets\/nzdusd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nzd-usd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NZDUSD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NZD\/USD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 2.5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"usdcad usd\/cad\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-4\"><a href=\"\/sv\/markets\/usdcad\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-cad\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/CAD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1.5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"eurgbp eur\/gbp\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-8\"><a href=\"\/sv\/markets\/eurgbp\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-gbp\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURGBP<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/GBP<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1.5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"eurjpy eur\/jpy\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-10\"><a href=\"\/sv\/markets\/eurjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 2<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"gbpjpy gbp\/jpy\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-11\"><a href=\"\/sv\/markets\/gbpjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 3<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"audjpy aud\/jpy\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-14\"><a href=\"\/sv\/markets\/audjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aud-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUDJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUD\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 2<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"audusd aud\/usd\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-7\"><a href=\"\/sv\/markets\/audusd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aud-usd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUDUSD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUD\/USD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"eurchf eur\/chf\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-9\"><a href=\"\/sv\/markets\/eurchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"euraud eur\/aud\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-12\"><a href=\"\/sv\/markets\/euraud\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-aud\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURAUD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/AUD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 7<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"eurcad eur\/cad\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-13\"><a href=\"\/sv\/markets\/eurcad\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-cad\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURCAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/CAD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 7<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"cadjpy cad\/jpy\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-15\"><a href=\"\/sv\/markets\/cadjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/cad-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CADJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">CAD\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 6<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"chfjpy chf\/jpy\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-16\"><a href=\"\/sv\/markets\/chfjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/chf-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CHFJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">CHF\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 6<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"usdhkd usd\/hkd\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-39\"><a href=\"\/sv\/markets\/usdhkd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-hkd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDHKD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/HKD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"usdzar usd\/zar\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-42\"><a href=\"\/sv\/markets\/usdzar\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-zar\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDZAR<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/ZAR<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"usdrub usd\/rub\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-44\"><a href=\"\/sv\/markets\/usdrub\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-rub\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDRUB<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/RUB<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"usdcnh usd\/cnh\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-45\"><a href=\"\/sv\/markets\/usdcnh\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-cnh\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCNH<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/CNH<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 10<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"audchf aud\/chf\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-46\"><a href=\"\/sv\/markets\/audchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aud-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUDCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUD\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"audcad aud\/cad\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-47\"><a href=\"\/sv\/markets\/audcad\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aud-cad\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUDCAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUD\/CAD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"audnzd aud\/nzd\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-48\"><a href=\"\/sv\/markets\/audnzd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aud-nzd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUDNZD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUD\/NZD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"eurnzd eur\/nzd\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-49\"><a href=\"\/sv\/markets\/eurnzd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-nzd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURNZD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/NZD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"gbpaud gbp\/aud\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-50\"><a href=\"\/sv\/markets\/gbpaud\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-aud\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPAUD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/AUD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"gbpchf gbp\/chf\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-51\"><a href=\"\/sv\/markets\/gbpchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"gbpnzd gbp\/nzd\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-52\"><a href=\"\/sv\/markets\/gbpnzd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-nzd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPNZD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/NZD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nzdcad nzd\/cad\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-53\"><a href=\"\/sv\/markets\/nzdcad\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nzd-cad\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NZDCAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NZD\/CAD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nzdchf nzd\/chf\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-54\"><a href=\"\/sv\/markets\/nzdchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nzd-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NZDCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NZD\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nzdjpy nzd\/jpy\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-55\"><a href=\"\/sv\/markets\/nzdjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nzd-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NZDJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NZD\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"cadchf cad\/chf\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-56\"><a href=\"\/sv\/markets\/cadchf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/cad-chf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CADCHF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">CAD\/CHF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"usdnok usd\/nok\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-57\"><a href=\"\/sv\/markets\/usdnok\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-nok\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDNOK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/NOK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"usdsek usd\/sek\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-58\"><a href=\"\/sv\/markets\/usdsek\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-sek\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDSEK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/SEK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"noksek nok\/sek\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-59\"><a href=\"\/sv\/markets\/noksek\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nok-sek\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NOKSEK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NOK\/SEK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"eurnok eur\/nok\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-60\"><a href=\"\/sv\/markets\/eurnok\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-nok\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURNOK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/NOK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"eursek eur\/sek\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-61\"><a href=\"\/sv\/markets\/eursek\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-sek\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURSEK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/SEK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 30<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"usdtry usd\/try\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-62\"><a href=\"\/sv\/markets\/usdtry\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-try\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDTRY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/TRY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"usdmxn usd\/mxn\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-63\"><a href=\"\/sv\/markets\/usdmxn\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-mxn\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDMXN<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/MXN<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"usdsgd usd\/sgd\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-64\"><a href=\"\/sv\/markets\/usdsgd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-sgd\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDSGD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/SGD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 3<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"gbpcad gbp\/cad\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-65\"><a href=\"\/sv\/markets\/gbpcad\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-cad\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPCAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/CAD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"zarjpy zar\/jpy\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-66\"><a href=\"\/sv\/markets\/zarjpy\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/zar-jpy\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">ZARJPY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">ZAR\/JPY<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 8<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"eurpln eur\/pln\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-68\"><a href=\"\/sv\/markets\/eurpln\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-pln\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURPLN<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/PLN<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 30<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"usdhuf usd\/huf\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-69\"><a href=\"\/sv\/markets\/usdhuf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-huf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDHUF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/HUF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"eurhuf eur\/huf\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-70\"><a href=\"\/sv\/markets\/eurhuf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eur-huf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURHUF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/HUF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"gbphuf gbp\/huf\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-71\"><a href=\"\/sv\/markets\/gbphuf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gbp-huf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPHUF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/HUF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 30<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"chfhuf chf\/huf\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-72\"><a href=\"\/sv\/markets\/chfhuf\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/chf-huf\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CHFHUF<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">CHF\/HUF<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 30<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"usdpln usd\/pln\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-73\"><a href=\"\/sv\/markets\/usdpln\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-pln\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDPLN<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/PLN<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"usdczk usd\/czk\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-82\"><a href=\"\/sv\/markets\/usdczk\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/82\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCZK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/CZK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 120<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"usdils usd\/ils\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-423\"><a href=\"\/sv\/markets\/usdils\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/423\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDILS<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/ILS<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"gbpils gbp\/ils\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-424\"><a href=\"\/sv\/markets\/gbpils\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/424\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GBPILS<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GBP\/ILS<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"eurils eur\/ils\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-425\"><a href=\"\/sv\/markets\/eurils\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/425\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EURILS<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUR\/ILS<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdcop usd\/cop\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-426\"><a href=\"\/sv\/markets\/usdcop\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/426\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCOP<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/COP<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 70000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdclp usd\/clp\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-427\"><a href=\"\/sv\/markets\/usdclp\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/427\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDCLP<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/CLP<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1300<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdkrw usd\/krw\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-428\"><a href=\"\/sv\/markets\/usdkrw\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/428\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDKRW<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/KRW<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 16000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdbrl usd\/brl\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-429\"><a href=\"\/sv\/markets\/usdbrl\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/429\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDBRL<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/BRL<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 9000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdpen usd\/pen\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-455\"><a href=\"\/sv\/markets\/usdpen\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/455\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDPEN<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/PEN<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 8000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdinr usd\/inr\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-456\"><a href=\"\/sv\/markets\/usdinr\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/456\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDINR<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/INR<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdphp usd\/php\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-458\"><a href=\"\/sv\/markets\/usdphp\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/458\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDPHP<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/PHP<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdtwd usd\/twd\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-459\"><a href=\"\/sv\/markets\/usdtwd\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/459\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDTWD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/TWD<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 8000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-5\" data-search_val=\"usdidr usd\/idr\" data-decade=\"5\">\n\t\t\t\t\t<td class=\"id-461\"><a href=\"\/sv\/markets\/usdidr\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/461\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDIDR<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/IDR<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 3000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-6\" data-search_val=\"usdthb usd\/thb\" data-decade=\"6\">\n\t\t\t\t\t<td class=\"id-460\"><a href=\"\/sv\/markets\/usdthb\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/460\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDTHB<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/THB<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 500<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-6\" data-search_val=\"usddkk usd\/dkk\" data-decade=\"6\">\n\t\t\t\t\t<td class=\"id-75\"><a href=\"\/sv\/markets\/usddkk\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usd-dkk\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDDKK<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">USD\/DKK<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 200<\/span>&nbsp;Pips<\/td><\/tr><\/tbody>\n                    <\/table><\/div><\/div><\/figure><button class=\"wp-block-etoro-instruments-fees-table-show-more\">Ladda fler<\/button><\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"\" class=\"wp-block-etoro-collapsable-item wp-block-etoro-collapsable-item-collapsable\"><div class=\"wp-block-etoro-collapsable-item-top-part\"><h2 class=\"wp-block-etoro-collapsable-item-title\"><small>R\u00e5varor<\/small><\/h2><\/div><div class=\"wp-block-etoro-collapsable-item-content-wrapper\"><div class=\"wp-block-etoro-collapsable-item-content\">\n\t<div class=\"wp-block-etoro-instruments-fees-table\" data-table-type=\"cat_35\">\n\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-wrapper\">\n\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-icon\">\n\t\t\t\t<input class=\"wp-block-etoro-instruments-fees-table-search\" type=\"text\" placeholder=\"S\u00f6k instrument\"\/>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<figure class=\"wp-block-table\">\n\t\t    <div class=\"wp-block-table-content\">\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-left\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-left\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-right\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-right\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-table\">\n\t\t            <table>\n                        <thead>\n                        <tr><th>R\u00e5varor<\/th><th>Fr\u00e5n 2 PIPs <e-tip><sup>Pip st\u00e5r f\u00f6r &#8220;procent i punkt&#8221;. En pip \u00e4r den minsta prisf\u00f6r\u00e4ndring som en viss v\u00e4xelkurs kan g\u00f6ra, och avser d\u00e4rf\u00f6r den allra sista siffran i ett pris. En pip anv\u00e4nds f\u00f6r att m\u00e4ta prisf\u00f6r\u00e4ndringen f\u00f6r en valuta i f\u00f6rh\u00e5llande till en annan.<\/sup><\/e-tip><\/th>\n                        <\/tr>\n                        <\/thead>\n                        <tbody>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"oil oil (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-17\"><a href=\"\/sv\/markets\/oil\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/oil\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">OIL<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Oil (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"gold gold (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-18\"><a href=\"\/sv\/markets\/gold\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/gold\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GOLD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Gold (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.025<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"silver silver (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-19\"><a href=\"\/sv\/markets\/silver\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/silver\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SILVER<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Silver (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.12<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"copper.fut copper (expiring future)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-21\"><a href=\"\/sv\/markets\/copper.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/copper\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">COPPER.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Copper (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 4<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"natgas natural gas (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-22\"><a href=\"\/sv\/markets\/natgas\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/natgas\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NATGAS<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Natural Gas (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.25<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"platinum platinum (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-40\"><a href=\"\/sv\/markets\/platinum\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/platinum\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">PLATINUM<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Platinum (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.3<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"palladium.fut palladium (expiring future)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-91\"><a href=\"\/sv\/markets\/palladium.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/91\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">PALLADIUM.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Palladium (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 40000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"sugar.fut sugar (expiring future)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-92\"><a href=\"\/sv\/markets\/sugar.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/92\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SUGAR.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Sugar (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"cotton.fut cotton (expiring future)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-93\"><a href=\"\/sv\/markets\/cotton.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/93\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">COTTON.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Cotton (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"cocoa.fut cocoa (expiring future)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-96\"><a href=\"\/sv\/markets\/cocoa.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/96\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">COCOA.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Cocoa (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1000<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"wheat.fut wheat (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-97\"><a href=\"\/sv\/markets\/wheat.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/97\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">WHEAT.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Wheat (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 175<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"oj.fut orange juice (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-311\"><a href=\"\/sv\/markets\/oj.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/311\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">OJ.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Orange Juice (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 250<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"soyoil.fut soybeans oil (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-317\"><a href=\"\/sv\/markets\/soyoil.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/317\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SoyOil.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Soybeans Oil (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 10<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"soymeal.fut soybeans meal (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-318\"><a href=\"\/sv\/markets\/soymeal.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/318\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SoyMeal.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Soybeans Meal (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"euronatgas.fut euro natgas (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-319\"><a href=\"\/sv\/markets\/euronatgas.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/319\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EuroNatGas.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Euro NatGas (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.5<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"oats.fut oats (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-324\"><a href=\"\/sv\/markets\/oats.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/324\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">OATS.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Oats (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 100<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"rice.fut rough rice (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-325\"><a href=\"\/sv\/markets\/rice.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/325\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">RICE.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Rough Rice (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 15<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"corn.fut corn (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-331\"><a href=\"\/sv\/markets\/corn.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/331\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Corn.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Corn (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 130<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"soybeans.fut soybeans (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-332\"><a href=\"\/sv\/markets\/soybeans.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/332\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Soybeans.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Soybeans (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 220<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"carbon.fut carbon emissions (expiring future)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-333\"><a href=\"\/sv\/markets\/carbon.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/333\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Carbon.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Carbon Emissions (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 25<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"coffee.fut coffee arabica (expiring future)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-334\"><a href=\"\/sv\/markets\/coffee.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/334\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Coffee.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Coffee Arabica (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 75<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"gasoline.fut gasoline (expiring future)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-335\"><a href=\"\/sv\/markets\/gasoline.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/335\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Gasoline.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Gasoline (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 80<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"heatingoil.fut heating oil (expiring future)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-336\"><a href=\"\/sv\/markets\/heatingoil.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/336\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">HeatingOil.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Heating Oil (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 80<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"livecattle.fut live cattle (expiring future)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-337\"><a href=\"\/sv\/markets\/livecattle.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/337\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">LiveCattle.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Live Cattle (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 15<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"leanhogs.fut lean hogs (expiring future)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-338\"><a href=\"\/sv\/markets\/leanhogs.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/338\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">LeanHogs.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Lean Hogs (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 20<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"lead lead (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-339\"><a href=\"\/sv\/markets\/lead\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/339\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">LEAD<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Lead (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 600<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"zinc zinc (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-340\"><a href=\"\/sv\/markets\/zinc\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/340\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">ZINC<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Zinc (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 700<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"eurooil brent oil (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-341\"><a href=\"\/sv\/markets\/eurooil\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/341\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EuroOIL<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Brent Oil (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 6<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nickel nickel (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-343\"><a href=\"\/sv\/markets\/nickel\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/343\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Nickel<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Nickel (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 3200<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"aluminum aluminum (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-344\"><a href=\"\/sv\/markets\/aluminum\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/344\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Aluminum<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Aluminum (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 700<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"coal.fut coal (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-379\"><a href=\"\/sv\/markets\/coal.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/379\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">COAL.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Coal (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 240<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"steel.fut steel (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-380\"><a href=\"\/sv\/markets\/steel.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/380\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">STEEL.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Steel (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1150<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"milk.fut class iii milk (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-381\"><a href=\"\/sv\/markets\/milk.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/381\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">MILK.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Class III Milk (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 10<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"lumber.fut lumber (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-382\"><a href=\"\/sv\/markets\/lumber.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/382\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">LUMBER.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Lumber (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 375<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"gasoil.fut low sulphur gasoil (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-387\"><a href=\"\/sv\/markets\/gasoil.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/387\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GasOil.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Low Sulphur Gasoil (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 85<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"power.fut german power (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-388\"><a href=\"\/sv\/markets\/power.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/388\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">POWER.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">German Power (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 50<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"uknatgas.fut uk nbp natural gas (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-389\"><a href=\"\/sv\/markets\/uknatgas.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/389\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">UKNatGas.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">UK NBP Natural Gas (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 450<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"canola.fut canola (expiring future)\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-422\"><a href=\"\/sv\/markets\/canola.fut\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/422\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CANOLA.FUT<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Canola (Expiring Future)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 100<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"ironore iron ore\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-557\"><a href=\"\/sv\/markets\/ironore\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/557\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">IronOre<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Iron Ore<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.30<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"rubber rubber\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-558\"><a href=\"\/sv\/markets\/rubber\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/558\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">RUBBER<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Rubber<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.30<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"gold.24-7 gold 24\/7\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-559\"><a href=\"\/sv\/markets\/gold.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/559\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GOLD.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GOLD 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.025<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"natgas.24-7 natgas 24\/7\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-782\"><a href=\"\/sv\/markets\/natgas.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/782\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NatGas.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NatGas 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n <\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"natgas.24-7 natgas 24\/7\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-782\"><a href=\"\/sv\/markets\/natgas.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/782\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NatGas.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NatGas 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.250<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"silver.24-7 silver 24\/7\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-783\"><a href=\"\/sv\/markets\/silver.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/783\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Silver.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Silver 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.120<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"oil.24-7 oil 24\/7\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-784\"><a href=\"\/sv\/markets\/oil.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/784\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">OIL.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Oil 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 5<\/span>&nbsp;Pips<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-4\" data-search_val=\"100.oz.silver.mar26 100-ounce silver mar 26 future\" data-decade=\"4\">\n\t\t\t\t\t<td class=\"id-208002\"><a href=\"\/sv\/markets\/100.oz.silver.mar26\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/208002\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">100.OZ.Silver.MAR26<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">100-Ounce Silver Mar 26 Future<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n <\/span>&nbsp;Pips<\/td><\/tr><\/tbody>\n                    <\/table><\/div><\/div><\/figure><button class=\"wp-block-etoro-instruments-fees-table-show-more\">Ladda fler<\/button><\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"\" class=\"wp-block-etoro-collapsable-item wp-block-etoro-collapsable-item-collapsable\"><div class=\"wp-block-etoro-collapsable-item-top-part\"><h2 class=\"wp-block-etoro-collapsable-item-title\"><small>Index<\/small><\/h2><\/div><div class=\"wp-block-etoro-collapsable-item-content-wrapper\"><div class=\"wp-block-etoro-collapsable-item-content\">\n\t<div class=\"wp-block-etoro-instruments-fees-table\" data-table-type=\"cat_43\">\n\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-wrapper\">\n\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-search-icon\">\n\t\t\t\t<input class=\"wp-block-etoro-instruments-fees-table-search\" type=\"text\" placeholder=\"S\u00f6k instrument\"\/>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<figure class=\"wp-block-table\">\n\t\t    <div class=\"wp-block-table-content\">\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-left\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-left\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-nav wp-block-table-content-nav-right\">\n\t\t            <div class=\"wp-block-table-content-nav-arrow wp-block-table-content-nav-arrow-right\"><\/div>\n\t\t        <\/div>\n\t\t        <div class=\"wp-block-table-content-table\">\n\t\t            <table>\n                        <thead>\n                        <tr><th>Index<\/th><th>Fr\u00e5n 0.02 punkter <e-tip><sup>En punkt \u00e4r en specifik m\u00e5ttenhet baserad p\u00e5 den underliggande tillg\u00e5ngen, eller den minsta prisr\u00f6relsen f\u00f6r instrumentet<\/sup><\/e-tip><\/th>\n                        <\/tr>\n                        <\/thead>\n                        <tbody>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"usdollar us dollar index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-25\"><a href=\"\/sv\/markets\/usdollar\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/usdollar\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">USDOLLAR<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">US Dollar Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.04<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"spx500 spx500 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-27\"><a href=\"\/sv\/markets\/spx500\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/spx500\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SPX500<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">SPX500 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.015<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"nsdq100 nasdaq100 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-28\"><a href=\"\/sv\/markets\/nsdq100\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/nsdq100\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NSDQ100<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NASDAQ100 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.015<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"dj30 dj30 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-29\"><a href=\"\/sv\/markets\/dj30\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/dj30\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">DJ30<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">DJ30 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 6<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"uk100 uk100 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-30\"><a href=\"\/sv\/markets\/uk100\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/uk100\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">UK100<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">UK100 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1.5<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"fra40 fra40 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-31\"><a href=\"\/sv\/markets\/fra40\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/fra40\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">FRA40<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">FRA40 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"ger40 ger40 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-32\"><a href=\"\/sv\/markets\/ger40\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/ger30\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GER40<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">GER40 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.015<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"aus200 aus200 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-33\"><a href=\"\/sv\/markets\/aus200\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/aus200\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AUS200<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AUS200 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 2<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"esp35 esp35 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-34\"><a href=\"\/sv\/markets\/esp35\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/esp35\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">ESP35<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">ESP35 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 7<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-0\" data-search_val=\"jpn225 jpn225 index (non expiry)\" data-decade=\"0\">\n\t\t\t\t\t<td class=\"id-36\"><a href=\"\/sv\/markets\/jpn225\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/jpn225\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">JPN225<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">JPN225 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 10<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"hkg50 hkg50 index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-38\"><a href=\"\/sv\/markets\/hkg50\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/hkg33\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">HKG50<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">HKG50 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 7<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"eustx50 eustx50 index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-43\"><a href=\"\/sv\/markets\/eustx50\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/eustx50\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">EUSTX50<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">EUSTX50 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 3<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"china50 chinaa50 index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-253\"><a href=\"\/sv\/markets\/china50\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/253\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">CHINA50<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">ChinaA50 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 12<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"sgx singapore index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-301\"><a href=\"\/sv\/markets\/sgx\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/301\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SGX<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Singapore Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.4<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"rty russell 2000 index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-310\"><a href=\"\/sv\/markets\/rty\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/310\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">RTY<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Russell 2000 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.5<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"italy40 italy 40 giants index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-321\"><a href=\"\/sv\/markets\/italy40\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/321\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Italy40<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Italy 40 Giants Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.05<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"switzerland20 switzerland 20 giants index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-322\"><a href=\"\/sv\/markets\/switzerland20\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/322\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Switzerland20<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Switzerland 20 Giants Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.05<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"nl25 netherlands 25 index (non expiry)\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-353\"><a href=\"\/sv\/markets\/nl25\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/353\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NL25<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Netherlands 25 Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.5<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"semiconductors semiconductors index\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-560\"><a href=\"\/sv\/markets\/semiconductors\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/560\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Semiconductors<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Semiconductors Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.3<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-1\" data-search_val=\"ai.leaders ai leaders index\" data-decade=\"1\">\n\t\t\t\t\t<td class=\"id-561\"><a href=\"\/sv\/markets\/ai.leaders\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/561\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">AI.Leaders<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">AI Leaders Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.3<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"cybersecurity cybersecurity index\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-562\"><a href=\"\/sv\/markets\/cybersecurity\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/562\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Cybersecurity<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Cybersecurity Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.50<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"quantum quantum computing index\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-563\"><a href=\"\/sv\/markets\/quantum\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/563\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Quantum<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Quantum Computing Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.50<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"goldminers gold miners index\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-564\"><a href=\"\/sv\/markets\/goldminers\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/564\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">GoldMiners<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Gold Miners Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.50<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"crypto10 crypto 10 index\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-624\"><a href=\"\/sv\/markets\/crypto10\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/624\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Crypto10<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Crypto 10 Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 1<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"canada60 canada 60 giants index (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-625\"><a href=\"\/sv\/markets\/canada60\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/625\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Canada60<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Canada 60 Giants Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.05<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"sweden30 sweden 30 giants index (non expiry)\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-626\"><a href=\"\/sv\/markets\/sweden30\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/626\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Sweden30<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Sweden 30 Giants Index (Non Expiry)<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.05<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nsdq100.24-7 nasdaq100 24\/7\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-686\"><a href=\"\/sv\/markets\/nsdq100.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/686\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">NSDQ100.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">NASDAQ100 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.015<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"sp.24-7 s&#038;p 24\/7\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-687\"><a href=\"\/sv\/markets\/sp.24-7\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/687\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">SP.24-7<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">S&#038;P 24\/7<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.015<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"nuclear nuclear index\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-690\"><a href=\"\/sv\/markets\/nuclear\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/690\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">Nuclear<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">Nuclear Index<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.5<\/span>&nbsp;%<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-2\" data-search_val=\"vix.jul26 vix jul 26 future\" data-decade=\"2\">\n\t\t\t\t\t<td class=\"id-704\"><a href=\"\/sv\/markets\/vix.jul26\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/704\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">VIX.JUL26<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">VIX Jul 26 Future<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.15<\/span>&nbsp;po\u00e4ng<\/td><\/tr>\n\t\t\t<tr class=\"tr-decade-3\" data-search_val=\"vix.aug26 vix aug 26 future\" data-decade=\"3\">\n\t\t\t\t\t<td class=\"id-705\"><a href=\"\/sv\/markets\/vix.aug26\" class=\"wp-block-etoro-instruments-fees-table-instrument-info\">\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-image\" style=\"background-image:url('https:\/\/etoro-cdn.etorostatic.com\/market-avatars\/705\/150x150.png')\"><\/div>\n\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-details\">\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-symbol\">VIX.AUG26<\/div>\n\t\t\t\t\t<div class=\"wp-block-etoro-instruments-fees-table-instrument-name\">VIX Aug 26 Future<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/a><\/td><td data-th=\"Spread\"><span class=\"spread_num\">Fr\u00e5n 0.15<\/span>&nbsp;po\u00e4ng<\/td><\/tr><\/tbody>\n                    <\/table><\/div><\/div><\/figure><button class=\"wp-block-etoro-instruments-fees-table-show-more\">Ladda fler<\/button><\/div><\/div><\/div><\/div>\n\n\n\n<div id=\"\" class=\"wp-block-etoro-collapsable-item wp-block-etoro-collapsable-item-not-collapsable\"><div class=\"wp-block-etoro-collapsable-item-top-part\"><h2 class=\"wp-block-etoro-collapsable-item-title\"><small>Aktier &amp; ETF:er (CFD:er)<\/small><\/h2><div class=\"wp-block-etoro-collapsable-item-title-value\">0.15%<\/div><\/div><div class=\"wp-block-etoro-collapsable-item-content-wrapper\"><div class=\"wp-block-etoro-collapsable-item-content\">\n<div class=\"wp-block-etoro-collapsable-item-frame\">\n<p>CFD-aktier \u00e4r transaktioner som inte inneb\u00e4r \u00e4gande av den underliggande tillg\u00e5ngen. CFD:er m\u00f6jligg\u00f6r funktioner som korta (SELL) ordrar och h\u00e4vst\u00e5ng.<br><br>Spread \u00e4r f\u00f6r b\u00e5da sidor (K\u00d6P och S\u00c4LJ).<br><br>* CFD-positioner i USA-listade aktier och ETF:er som priss\u00e4tts till 3 USD eller mindre (baserat p\u00e5 st\u00e4ngningskursen p\u00e5 eToros plattform f\u00f6r den sista handelsdagen i f\u00f6reg\u00e5ende vecka) kommer att medf\u00f6ra en avgift p\u00e5 2 cent per enhet.<\/p>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<div id=\"\" class=\"wp-block-etoro-collapsable-item wp-block-etoro-collapsable-item-not-collapsable\"><div class=\"wp-block-etoro-collapsable-item-top-part\"><h2 class=\"wp-block-etoro-collapsable-item-title\"><small>Kryptovalutor (CDF:er)<\/small><\/h2><div class=\"wp-block-etoro-collapsable-item-title-value\">1%<\/div><\/div><div class=\"wp-block-etoro-collapsable-item-content-wrapper\"><div class=\"wp-block-etoro-collapsable-item-content\">\n<div class=\"wp-block-etoro-collapsable-item-frame\">\n<p><strong>Blankningsorder och h\u00e4vst\u00e5ngspositioner i krypto utf\u00f6rs som CFD:er. P\u00e5 grund av lagstadgade krav kan vissa icke-h\u00e4vst\u00e5ngsk\u00f6pta positioner i krypto utf\u00f6ras som CFD:er.<\/strong><br><br>I din portf\u00f6lj inkluderar P&amp;L den k\u00f6pavgift p\u00e5 1 % som du just betalat och den s\u00e4ljavgift p\u00e5 1 % som du kommer att betala n\u00e4r du st\u00e4nger positionen.<br><br>Observera: N\u00e4r du st\u00e4nger positionen justeras f\u00f6rs\u00e4ljningsavgiften f\u00f6r att \u00e5terspegla marknadspriset f\u00f6r kryptotillg\u00e5ngen vid den tidpunkten.<\/p>\n<\/div>\n<\/div><\/div><\/div>\n\n\n\n<p class=\"is-style-disclaimer\">*Avgifter som genereras fr\u00e5n spreaden debiteras vid st\u00e4ngning av en position. Det kan finnas tillf\u00e4llen d\u00e5 marknadsf\u00f6rh\u00e5llandena g\u00f6r att spreadarna breddas ut\u00f6ver de spreads som visas.<br>*Spreads indikerar l\u00e4gsta m\u00f6jliga scenario. Spreadarna \u00e4r variabla och kan fluktuera.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<a class=\"e-cta e-cta-primary\" href=\"https:\/\/www.etoro.com\/sv\/accounts\/sign-up?funnelfromid=56\">B\u00f6rja handla<\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-etoro-related-pages has-carbon-olive-background-color wp-etoro-block-related-pages\"><div class=\"wp-etoro-block-related-pages-to-center\"><div class=\"wp-etoro-block-related-pages-menu-name\">Relaterade sidor:<\/div><div class=\"wp-etoro-block-related-pages-list-container\"><div class=\"wp-etoro-block-related-pages-arrow-left\"><button><\/button><\/div><div class=\"wp-etoro-block-related-pages-list\">\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/trading\/fees\/\">eToro avgifter<\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/trading\/market-hours-and-events\/\">\u00d6ppettider f\u00f6r marknaden<\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/trading\/fees\/conversion\">Avgifter f\u00f6r valutakonvertering<\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-overnight-fees\/\">Nattavgifter<\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/crypto\/coin-transfer\/\">\u00d6verf\u00f6ring av kryptovalutor<\/a><\/div>\n\n\n\n<div class=\"wp-etoro-block-related-pages-link\"><a class=\"wp-etoro-block-related-page-link\" href=\"https:\/\/www.etoro.com\/sv\/crypto\/pricing-explained\/\">F\u00f6rklaring till priss\u00e4ttning av kryptovalutor<\/a><\/div>\n<\/div><div class=\"wp-etoro-block-related-pages-arrow-right\"><button><\/button><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Spreaden \u00e4r skillnaden mellan k\u00f6p- och s\u00e4ljkursen f\u00f6r en viss tillg\u00e5ng.Spreads \u00e4r ett vanligt s\u00e4tt f\u00f6r handelsplattformar att ta ut avgifter.<\/p>\n","protected":false},"author":39,"featured_media":832723,"parent":139277,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"sticky_cta_settings":"","footnotes":""},"asset_type":[],"class_list":["post-854950","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<title>Spreads f\u00f6r CFD-handel hos eToro<\/title>\n<meta name=\"description\" content=\"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spreads f\u00f6r CFD-handel hos eToro\" \/>\n<meta property=\"og:description\" content=\"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950\" \/>\n<meta property=\"og:site_name\" content=\"eToro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eToro\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T08:48:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eToro\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/\",\"url\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/\",\"name\":\"Spreads f\u00f6r CFD-handel hos eToro\",\"isPartOf\":{\"@id\":\"https:\/\/www.etoro.com\/sv\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png\",\"datePublished\":\"2024-01-18T07:52:20+00:00\",\"dateModified\":\"2024-03-19T08:48:09+00:00\",\"description\":\"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform\",\"breadcrumb\":{\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#breadcrumb\"},\"inLanguage\":\"sv\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv\",\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage\",\"url\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png\",\"contentUrl\":\"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/www.etoro.com\/sv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HANDEL\",\"item\":\"https:\/\/www.etoro.com\/sv\/trading\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avgifter och kostnader\",\"item\":\"https:\/\/www.etoro.com\/sv\/trading\/fees\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"CDF-spreads\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.etoro.com\/sv\/#website\",\"url\":\"https:\/\/www.etoro.com\/sv\/\",\"name\":\"eToro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.etoro.com\/sv\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.etoro.com\/sv\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv\"},[]]}<\/script>","yoast_head_json":{"title":"Spreads f\u00f6r CFD-handel hos eToro","description":"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950","og_locale":"sv_SE","og_type":"article","og_title":"Spreads f\u00f6r CFD-handel hos eToro","og_description":"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform","og_url":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950","og_site_name":"eToro","article_publisher":"https:\/\/www.facebook.com\/eToro\/","article_modified_time":"2024-03-19T08:48:09+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eToro","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/","url":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/","name":"Spreads f\u00f6r CFD-handel hos eToro","isPartOf":{"@id":"https:\/\/www.etoro.com\/sv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage"},"image":{"@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage"},"thumbnailUrl":"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png","datePublished":"2024-01-18T07:52:20+00:00","dateModified":"2024-03-19T08:48:09+00:00","description":"Ta reda p\u00e5 mer om spreads och hur de debiteras n\u00e4r du handlar CFD:er p\u00e5 eToros plattform","breadcrumb":{"@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#breadcrumb"},"inLanguage":"sv","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/"]}]},{"@type":"ImageObject","inLanguage":"sv","@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#primaryimage","url":"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png","contentUrl":"https:\/\/www.etoro.com\/wp-content\/uploads\/2024\/01\/Featured-image-1200x630-2.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.etoro.com\/sv\/trading\/fees\/cfd-spreads\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/www.etoro.com\/sv\/"},{"@type":"ListItem","position":2,"name":"HANDEL","item":"https:\/\/www.etoro.com\/sv\/trading\/"},{"@type":"ListItem","position":3,"name":"Avgifter och kostnader","item":"https:\/\/www.etoro.com\/sv\/trading\/fees\/"},{"@type":"ListItem","position":4,"name":"CDF-spreads"}]},{"@type":"WebSite","@id":"https:\/\/www.etoro.com\/sv\/#website","url":"https:\/\/www.etoro.com\/sv\/","name":"eToro","description":"","publisher":{"@id":"https:\/\/www.etoro.com\/sv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.etoro.com\/sv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv"},[]]}},"_links":{"self":[{"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950"}],"collection":[{"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/comments?post=854950"}],"version-history":[{"count":0,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/854950\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/pages\/139277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/media\/832723"}],"wp:attachment":[{"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/media?parent=854950"}],"wp:term":[{"taxonomy":"asset_type","embeddable":true,"href":"https:\/\/www.etoro.com\/sv\/wp-json\/wp\/v2\/asset_type?post=854950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}